{"id":40,"date":"2021-03-07T13:52:34","date_gmt":"2021-03-07T13:52:34","guid":{"rendered":"https:\/\/fredensborgslotskirkespigekor.dk\/?page_id=40"},"modified":"2026-03-04T16:02:19","modified_gmt":"2026-03-04T15:02:19","slug":"booking","status":"publish","type":"page","link":"https:\/\/fredensborgslotskirkespigekor.dk\/en\/booking\/","title":{"rendered":"Booking"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"40\" class=\"elementor elementor-40\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6766ec6 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6766ec6\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-281d3aa\" data-id=\"281d3aa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-44b8018 elementor-widget elementor-widget-heading\" data-id=\"44b8018\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Booking<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-be061a5 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"be061a5\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-016c6b6\" data-id=\"016c6b6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-12b3575 elementor-widget elementor-widget-text-editor\" data-id=\"12b3575\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>The Danish Girls' Choir of Fredensborg Chapel can be booked to sing at private occasions and corporate events.<\/p><p>We love to sing in unconventional venues and to get close to the audience at receptions, company parties, anniversaries, birthdays or other special occasions where the settings are right for a solemn moment with beautiful voices.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fdff1e5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fdff1e5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ce4a491\" data-id=\"ce4a491\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-309a4e1 elementor-widget elementor-widget-video\" data-id=\"309a4e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;hosted&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-hosted-video elementor-wrapper elementor-open-inline\">\n\t\t\t\t\t<video class=\"elementor-video\" src=\"https:\/\/fredensborgslotskirkespigekor.dk\/wp-content\/uploads\/FSP-BOOKING-VIDEO.mp4\" controls=\"\" preload=\"metadata\" controlslist=\"nodownload\"><\/video>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e2c9ea1 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e2c9ea1\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-48bf02b\" data-id=\"48bf02b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d317802 elementor-widget elementor-widget-heading\" data-id=\"d317802\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Repertoire<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fd7a934 elementor-widget elementor-widget-text-editor\" data-id=\"fd7a934\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">When booking the Girls' Choir there is an extensive repertoire to choose from.\nIf you have a special request, please let us know well in advance and we will try our best to accommodate your wishes for the occation. \nPlease take a look at our repertoire below for inspiration:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4fb5c51 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4fb5c51\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-78b1664\" data-id=\"78b1664\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8b02718 elementor-widget elementor-widget-image\" data-id=\"8b02718\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/fredensborgslotskirkespigekor.dk\/wp-content\/uploads\/Billede-06.10.2024-18.12.52-1-e1728399228607.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"Billede 06.10.2024, 18.12.52\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Njc2NiwidXJsIjoiaHR0cHM6XC9cL2ZyZWRlbnNib3Jnc2xvdHNraXJrZXNwaWdla29yLmRrXC93cC1jb250ZW50XC91cGxvYWRzXC9CaWxsZWRlLTA2LjEwLjIwMjQtMTguMTIuNTItMS1lMTcyODM5OTIyODYwNy5qcGcifQ%3D%3D\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"930\" height=\"620\" src=\"https:\/\/fredensborgslotskirkespigekor.dk\/wp-content\/uploads\/Billede-06.10.2024-18.12.52-1-e1728399228607-930x620.jpg\" class=\"attachment-neve-blog size-neve-blog wp-image-6766\" alt=\"\" srcset=\"https:\/\/fredensborgslotskirkespigekor.dk\/wp-content\/uploads\/Billede-06.10.2024-18.12.52-1-e1728399228607-930x620.jpg 930w, https:\/\/fredensborgslotskirkespigekor.dk\/wp-content\/uploads\/Billede-06.10.2024-18.12.52-1-e1728399228607-300x199.jpg 300w, https:\/\/fredensborgslotskirkespigekor.dk\/wp-content\/uploads\/Billede-06.10.2024-18.12.52-1-e1728399228607-18x12.jpg 18w\" sizes=\"(max-width: 930px) 100vw, 930px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Foto: MNS<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-88fe782 elementor-widget elementor-widget-heading\" data-id=\"88fe782\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Danish songs<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df316d3 elementor-widget elementor-widget-text-editor\" data-id=\"df316d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><em>Danmark nu blunder<\/em><\/li><li><em>Den bl\u00e5 anemone<\/em><\/li><li><em>Der er et yndigt land<\/em><\/li><li><em>Det er hvidt herude<\/em><\/li><li><em>Det er i dag et vejr<\/em><\/li><li><i>Det lysner over agres felt<\/i><\/li><li><em>Du danske sommer<\/em><\/li><li><em>Du er som s\u00e5dan en rose<\/em><\/li><li><em>En yndig og frydefuld sommertid<\/em><\/li><li><em>Et hav, der vugger sig til ro nu<\/em><\/li><li><em>Et hav s\u00e5 glitrende og stille<\/em><\/li><li><em>Fo ajle (Opv\u00e5vni)<\/em><\/li><li><em>Fred hviler<\/em><\/li><li><em>I Danmark er jeg f\u00f8dt<\/em><\/li><li><em>Jeg plukker fl\u00f8jlsgr\u00e6s<\/em><\/li><li><em>Lyset springer pludselig ud\u00a0<\/em><\/li><li><em>Min Jesus lad mit hjerte f\u00e5<\/em><\/li><li><em>Morgensang af Elverskud (N.W.Gade)\u00a0\u00a0<\/em><\/li><li><em>Norwegian sunset<\/em><\/li><li><em>Nu er jord og himmel stille<\/em><\/li><li><em>Nu falmer skoven<\/em><\/li><li><em>P\u00e5skeblomst<\/em><\/li><li><em>Se nu stiger solen<\/em><\/li><li><em>Sensommervise<\/em><\/li><li><em>Septembers himmel<\/em><\/li><li><em>Sig n\u00e6rmer tiden<\/em><\/li><li><em>Sneflokke kommer vrimlende<\/em><\/li><li><em>Solen er s\u00e5 r\u00f8d, mor<\/em><\/li><li><em>Sommersalme (Det dufter lysegr\u00f8nt)<\/em><\/li><li><em>Sov s\u00f8dt barnlille<\/em><\/li><li><em>Stille hjerte sol g\u00e5r ned<\/em><\/li><li><em>S\u00e6nk kun dit hoved du blomst<\/em><\/li><li><em>S\u00e5 tag mit hjerte (Michael Bojesen)<\/em><\/li><li><em>Tit er jeg glad<\/em><\/li><li><em>Tunge m\u00f8rke natteskyer<\/em><\/li><li><em>Underlige aftenlufte<\/em><\/li><li><em>Yndigt dufter Danmark<\/em><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-771e037\" data-id=\"771e037\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-090f686 elementor-widget elementor-widget-image\" data-id=\"090f686\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/fredensborgslotskirkespigekor.dk\/wp-content\/uploads\/image004.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"image004\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjY5MywidXJsIjoiaHR0cHM6XC9cL2ZyZWRlbnNib3Jnc2xvdHNraXJrZXNwaWdla29yLmRrXC93cC1jb250ZW50XC91cGxvYWRzXC9pbWFnZTAwNC5qcGcifQ%3D%3D\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"930\" height=\"620\" src=\"https:\/\/fredensborgslotskirkespigekor.dk\/wp-content\/uploads\/image004-930x620.jpg\" class=\"attachment-neve-blog size-neve-blog wp-image-6693\" alt=\"\" srcset=\"https:\/\/fredensborgslotskirkespigekor.dk\/wp-content\/uploads\/image004-930x620.jpg 930w, https:\/\/fredensborgslotskirkespigekor.dk\/wp-content\/uploads\/image004-300x200.jpg 300w, https:\/\/fredensborgslotskirkespigekor.dk\/wp-content\/uploads\/image004-1024x683.jpg 1024w, https:\/\/fredensborgslotskirkespigekor.dk\/wp-content\/uploads\/image004-768x512.jpg 768w, https:\/\/fredensborgslotskirkespigekor.dk\/wp-content\/uploads\/image004-18x12.jpg 18w, https:\/\/fredensborgslotskirkespigekor.dk\/wp-content\/uploads\/image004.jpg 1086w\" sizes=\"(max-width: 930px) 100vw, 930px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Fotograf Niels Dreijer<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a085a9d elementor-widget elementor-widget-heading\" data-id=\"a085a9d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Classic songs<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d9bd0a1 elementor-widget elementor-widget-text-editor\" data-id=\"d9bd0a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><em>A spotless rose (Mealor)<\/em><\/li><li><em>Abendlied (Rheinberger)<\/em><\/li><li><em>Amen Alleluia (Lang)<\/em><\/li><li><em>Ave Generosa (Gjeilo)<\/em><\/li><li><em>Ave Maria (MacIntyre)<\/em><\/li><li><em>Dies Irae (Trotta)<\/em><\/li><li><em>Even when he is silent (Arnesen)<\/em><\/li><li><em>Hebe deine Augen auf (Mendelssohn)<\/em><\/li><li><em>I denna ljuva sommartid (Arnesen)<\/em><\/li><li><em>In Pace (Orlando di Lassus)<\/em><\/li><li><em>Jesu bleibet meine Freude (Bach)<\/em><\/li><li><em>Laudate Pueri (Hasse)<\/em><\/li><li><em>Northern Ligths (Gjeilo)<\/em><\/li><li><em>O magnum mysterium (Lauridsen)<\/em><\/li><li><em>O radiant Dawn (MacMillan)<\/em><\/li><li><em>O salutaris Hosia (Esenwalds)<\/em><\/li><li><em>Panis Angelicus (Cesar Franck)<\/em><\/li><li><em>Tota pulchra es (Durufle)<\/em><\/li><li><em>Ubi Caritas (Gjeilo &amp; Arnesen)<\/em><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d48f5b7 elementor-widget elementor-widget-spacer\" data-id=\"d48f5b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fc53eb5 elementor-widget elementor-widget-heading\" data-id=\"fc53eb5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Major works<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d4e1d05 elementor-widget elementor-widget-text-editor\" data-id=\"d4e1d05\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div>(best suited in churches)<i><br \/><\/i><\/div><ul><li><em style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight ); background-color: var( --e-global-color-nvsitebg ); letter-spacing: 0px;\">A Ceremony of Carols (Britten)<\/em><\/li><li><em>Gloria (Vivaldi)<\/em><\/li><li><em>Kyrie (Vivaldi)<\/em><\/li><li><em>Requiem (Faur\u00e9)<\/em><\/li><li><em>Stabat Mater (Pergolesi)<\/em><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-94c04c6\" data-id=\"94c04c6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d468f48 elementor-widget elementor-widget-image\" data-id=\"d468f48\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/fredensborgslotskirkespigekor.dk\/wp-content\/uploads\/IMG_8023-scaled-e1728399402473.jpeg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"IMG_8023\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Njc2MCwidXJsIjoiaHR0cHM6XC9cL2ZyZWRlbnNib3Jnc2xvdHNraXJrZXNwaWdla29yLmRrXC93cC1jb250ZW50XC91cGxvYWRzXC9JTUdfODAyMy1zY2FsZWQuanBlZyJ9\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"930\" height=\"620\" src=\"https:\/\/fredensborgslotskirkespigekor.dk\/wp-content\/uploads\/IMG_8023-930x620.jpeg\" class=\"attachment-neve-blog size-neve-blog wp-image-6760\" alt=\"\" srcset=\"https:\/\/fredensborgslotskirkespigekor.dk\/wp-content\/uploads\/IMG_8023-930x620.jpeg 930w, https:\/\/fredensborgslotskirkespigekor.dk\/wp-content\/uploads\/IMG_8023-16x12.jpeg 16w\" sizes=\"(max-width: 930px) 100vw, 930px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Foto: MNS<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eac5faa elementor-widget elementor-widget-heading\" data-id=\"eac5faa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Entertainment songs<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f505851 elementor-widget elementor-widget-text-editor\" data-id=\"f505851\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><em>7 Years (Lukas Graham)<\/em><\/li><li><em>And so it goes (Joel)<\/em><\/li><li><em>As it was (Harry Styles)<\/em><\/li><li><em>Because (Beatles)<\/em><\/li><li><em>Dansevise\u00a0<\/em><\/li><li><em>De n\u00e6re ting (Olavac)<\/em><\/li><li><em>Den allersidste dans<\/em><\/li><li><em>Du er\u00a0<\/em><\/li><li><em>Everywhere (Fleetwood Mac)<\/em><\/li><li><em>Fald min engel (TV2)<\/em><\/li><li><em>Flowers (Miley Cyrus)<\/em><\/li><li><em>Flyv fugl (Rasmus Seebach)<\/em><\/li><li><em>Forelsket i K\u00f8benhavn<\/em><\/li><li><em>For once in my life (Stevie Wonder)<\/em><\/li><li><em>For\u00e5rsdag (Anne Linnet)<\/em><\/li><li><em>Frit land (Ulige numre)<\/em><\/li><li><em>Frostsalme <\/em><em>(Hymns from Nineveh)<\/em><\/li><li><em>Gem et lille smil<\/em><\/li><li><em>Hallelujah (Leonard Cohen)<\/em><\/li><li><em>Hjem (Sanne Salomonsen)<\/em><\/li><li><em>Lyse n\u00e6tter (Alberte Winding)<\/em><\/li><li><em>My funny valentine (Rodgers\/ Hart)<\/em><\/li><li><em>Norwegian sunset (Bent Fabricius-Bjerre)<\/em><\/li><li><em>N\u00e6r (Michael Falch)<\/em><\/li><li><em>N\u00e5r jeg bliver gammel (Gnags)<\/em><\/li><li><em>Right next to the Right One (Christensen)<\/em><\/li><li><em>River (Joni Mitchell)<\/em><\/li><li><em>Riverside (Agnes Obel)<\/em><\/li><li><em>Rullefald (Pil)<\/em><\/li><li><em>Stormy weather<\/em><\/li><li><em>Supermarket flowers (Ed Sheeran)<\/em><\/li><li><em>The rainbow connection<\/em><\/li><li><em>Verden er i farver (Lis S\u00f8rensen)<\/em><\/li><li><em>When you say nothing at all (Keating)<\/em><\/li><li><em>Wintersong (Sara Bareilles)<\/em><\/li><li><em>You take my breath away (Mercury)<\/em><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-721815e elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"721815e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6ce3d14\" data-id=\"6ce3d14\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-36be4ad elementor-widget elementor-widget-heading\" data-id=\"36be4ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Get an informal offer<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ece3ee elementor-widget elementor-widget-text-editor\" data-id=\"3ece3ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Should The Danish Girls Choir of Fredensborg Chapel have sparked an interest, we are happy to attend to booking inquiries<\/p><p>The price depends on several factors \u2013 occasion, day of the week, time, number of songs, location and the number of guests.<\/p><p>If you fill out the form below, we will contact you in order to attune to your expectations before we prepare an offer.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d45d0b6 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"d45d0b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/fredensborgslotskirkespigekor.dk\/en\/faa-et-tilbud\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">get an offer<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bc686ba elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bc686ba\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-55ddcb8\" data-id=\"55ddcb8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f48a303 elementor-widget elementor-widget-heading\" data-id=\"f48a303\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Amazing memories of these places<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9d913d3 elementor-arrows-position-outside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"9d913d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;5&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;pause_on_hover&quot;:&quot;no&quot;,&quot;speed&quot;:400,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:67,&quot;sizes&quot;:[]},&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Billedkarussel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 13\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/fredensborgslotskirkespigekor.dk\/wp-content\/uploads\/horten-300x53.png\" alt=\"Horten Advokater - Logo\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 13\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/fredensborgslotskirkespigekor.dk\/wp-content\/uploads\/CPH-Business-300x54.png\" alt=\"CPH Business - Logo\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 13\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/fredensborgslotskirkespigekor.dk\/wp-content\/uploads\/museum-for-papirkunst-300x94.png\" alt=\"Museum for Papirkunst - Logo\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 13\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/fredensborgslotskirkespigekor.dk\/wp-content\/uploads\/it-branchen-logo-2019-hvid-baggrund-600-300x106.png\" alt=\"IT Brancheforeningen - Logo\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 13\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/fredensborgslotskirkespigekor.dk\/wp-content\/uploads\/gadens-boern-300x109.png\" alt=\"Gadens B\u00f8rn - Logo\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 13\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/fredensborgslotskirkespigekor.dk\/wp-content\/uploads\/Nivaagaards-Malerisamling-LOGO-673x349-1-300x79.jpg\" alt=\"Nivaagaards Malerisamling - Logo\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 of 13\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/fredensborgslotskirkespigekor.dk\/wp-content\/uploads\/Valby-Kirke-1-300x221.jpg\" alt=\"Valby Kirke\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 of 13\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/fredensborgslotskirkespigekor.dk\/wp-content\/uploads\/Burre-gruppen-1-300x231.jpg\" alt=\"Burre-gruppen\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 of 13\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/fredensborgslotskirkespigekor.dk\/wp-content\/uploads\/Helsingoer-Domkirke-300x102.png\" alt=\"Helsing\u00f8r Domkirke - Logo\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 of 13\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/fredensborgslotskirkespigekor.dk\/wp-content\/uploads\/Marielyst-Hoejskole-300x143.png\" alt=\"Marielyst H\u00f8jskole - Logo\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 of 13\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/fredensborgslotskirkespigekor.dk\/wp-content\/uploads\/Vedbaek-Kirke.jpg\" alt=\"Vedb\u00e6k Kirke - Logo\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 of 13\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/fredensborgslotskirkespigekor.dk\/wp-content\/uploads\/Koldinghus.png\" alt=\"Koldinghus - Logo\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 of 13\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/fredensborgslotskirkespigekor.dk\/wp-content\/uploads\/Skagens-Museum-152x300.png\" alt=\"Skagens Museum - Logo\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Booking Fredensborg Slotskirkes Pigekor kan bookes til at synge ved private anledninger og firmaevents. Vi elsker at komme ud at synge og f\u00e5 kontakt med publikum i forbindelse receptioner, firmafester, jubil\u00e6er, runde f\u00f8dselsdage eller andre specielle lejligheder, hvor rammerne fordrer et \u00f8jebliks fordybelse i vellyd af smukke stemmer. https:\/\/fredensborgslotskirkespigekor.dk\/wp-content\/uploads\/FSP-BOOKING-VIDEO.mp4 Repertoire N\u00e5r du booker Pigekoret, er&hellip;&nbsp;<a href=\"https:\/\/fredensborgslotskirkespigekor.dk\/en\/booking\/\" rel=\"bookmark\">Read More &raquo;<span class=\"screen-reader-text\">Booking<\/span><\/a><\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"neve_meta_sidebar":"full-width","neve_meta_container":"","neve_meta_enable_content_width":"on","neve_meta_content_width":100,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"on","footnotes":""},"class_list":["post-40","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/fredensborgslotskirkespigekor.dk\/en\/wp-json\/wp\/v2\/pages\/40","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fredensborgslotskirkespigekor.dk\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fredensborgslotskirkespigekor.dk\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fredensborgslotskirkespigekor.dk\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fredensborgslotskirkespigekor.dk\/en\/wp-json\/wp\/v2\/comments?post=40"}],"version-history":[{"count":313,"href":"https:\/\/fredensborgslotskirkespigekor.dk\/en\/wp-json\/wp\/v2\/pages\/40\/revisions"}],"predecessor-version":[{"id":7705,"href":"https:\/\/fredensborgslotskirkespigekor.dk\/en\/wp-json\/wp\/v2\/pages\/40\/revisions\/7705"}],"wp:attachment":[{"href":"https:\/\/fredensborgslotskirkespigekor.dk\/en\/wp-json\/wp\/v2\/media?parent=40"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}